{"id":2688,"date":"2017-11-07T00:00:00","date_gmt":"2017-11-07T00:00:00","guid":{"rendered":"https:\/\/www.mariventyachts.com\/nueva-fjord-36-xpress\/"},"modified":"2024-11-20T16:25:26","modified_gmt":"2024-11-20T16:25:26","slug":"nueva-fjord-36-xpress","status":"publish","type":"post","link":"https:\/\/www.mariventyachts.com\/es\/nueva-fjord-36-xpress\/","title":{"rendered":"NUEVA FJORD 36 XPRESS"},"content":{"rendered":"<p>Tras la feria n\u00e1utica internacional de Barcelona, hoy queremos dedicarle unas l\u00edneas al nuevo modelo de Fjord, la 36 Xpress. Un modelo que presentamos en primicia para Espa\u00f1a, tras su exhibici\u00f3n en la Feria N\u00e1utica de Cannes el pasado mes de Septiembre.<\/p>\n<p>A priori, este modelo basado en el casco de 36 pies lanzado al mercado en 2011 en su versi\u00f3n Open, ven\u00eda b\u00e1sicamente a completar la gama por debajo de los doce metros con una motorizaci\u00f3n fuera borda. Pero a la vista del resultado final, hemos podido ver que las mejoras introducidas por el astillero alem\u00e1n van m\u00e1s all\u00e1 de un cambio de motorizaci\u00f3n.<\/p>\n<p>Por un lado, es obvio que la Xpress, con los motores fuera borda aporta tres valores principales. Mejora de la motorizaci\u00f3n, pudiendo montar dos motores de 350CV lo cual aumenta en 100CV la motorizaci\u00f3n m\u00e1s potente de su versi\u00f3n predecesora, la 36 Open. La disminuci\u00f3n del peso al cambiar los bloques de motor D4 de Volvo por los fuera borda, y la accesibilidad a zonas de calado reducido.<\/p>\n<p>Estos tres argumentos ya son por s\u00ed mismo muy significativos, ya que aportan unas mejoras muy importantes al modelo. La velocidad punta a subido hasta pr\u00e1cticamente 45 nudos. Mientras que el consumo, si bien es obvio que ha aumentado, se puede controlar con facilidad. Con la reducci\u00f3n de peso, la 36 Xpress arranca al planeo con agilidad pudiendo mantenerlo con un r\u00e9gimen de revoluciones bajo si lo que se pretende es controlar el gasto en combustible.<\/p>\n<p>Adem\u00e1s existen dos elementos a\u00f1adidos que aportan a\u00fan m\u00e1s versatilidad a la Xpress. Por un lado, la antigua sala de motores se ha convertido en un espacio de estiba enorme, muy pr\u00e1ctico y necesario en una embarcaci\u00f3n con capacidad para 12 personas. Y por otro lado, la cubierta de popa a\u00f1adiendo una dinette convertible al estilo de la Fjord 40 Open. As\u00ed, la popa, donde la manga es m\u00e1s generosa, permite reunir c\u00f3modamente a 8 personas sentadas, y al mismo tiempo convertirse en un solarium m\u00e1s grande si cabe que el de 36 Open. As\u00ed pues hemos trasladado la vida social a una zona m\u00e1s amplia y mejor protegida del sol por los toldos con tangones de Fjord, cerca de la cocina (en opci\u00f3n).<\/p>\n<p>La deportividad y polivalencia de la Xpress pasa a ser su punto fuerte cubriendo un rango de un utilizaci\u00f3n m\u00e1s amplio. Desde el amante de la sensaciones fuertes y los deportes n\u00e1uticos, pasando por las salidas en grupo para disfrutar de un d\u00eda en familia o con amigos con total comodidad. La practicidad de los motores fuera borda tanto a la hora de acercarse a aguas someras de playas y calas, o de su mantenimiento, compensa de sobra la p\u00e9rdida de la gran plataforma de ba\u00f1o. Adem\u00e1s el astillero ofrece en opci\u00f3n dos plataformas de ba\u00f1o de mayor superficie a lado y lado de los motores.<\/p>\n<p>Finalmente, cabe mencionar la posibilidad de escoger la motorizaci\u00f3n que el armador prefiera manteniendo un precio final m\u00e1s del orden de treinta mil euros m\u00e1s bajo que la versi\u00f3n Open. La cabina con una cama doble y un aseo completamente separado sigue ofreciendo la privacidad y estilo de la gama con gran variedad de acabos interiores. As\u00ed este modelo sigue ofreciendo la posibilidad de dormir c\u00f3modamente en ella durante una breve escapada de fin de semana.<\/p>\n<p>A todas vistas, la nueva versi\u00f3n de 36 pies es un valor en alza que aporta muchas soluciones manteniendo el concepto de la marca Fjord y la calidad del astillero Hanse.<\/p>\n<p><strong>Departamento de ventas<\/strong><\/p>\n<p><strong>Marivent Yachts<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras la feria n\u00e1utica internacional de Barcelona, hoy queremos dedicarle unas l\u00edneas al nuevo modelo de Fjord, la 36 Xpress.<\/p>\n","protected":false},"author":1,"featured_media":2340,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[],"class_list":["post-2688","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categorizar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>NUEVA FJORD 36 XPRESS - Marivent Yachts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mariventyachts.com\/es\/nueva-fjord-36-xpress\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"NUEVA FJORD 36 XPRESS - Marivent Yachts\" \/>\n<meta property=\"og:description\" content=\"Tras la feria n\u00e1utica internacional de Barcelona, hoy queremos dedicarle unas l\u00edneas al nuevo modelo de Fjord, la 36 Xpress.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mariventyachts.com\/es\/nueva-fjord-36-xpress\/\" \/>\n<meta property=\"og:site_name\" content=\"Marivent Yachts\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/mariventyachts\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-07T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-20T16:25:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mariventyachts.com\/wp-content\/uploads\/Fjord_36_xpress_exterior_Featured2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"956\" \/>\n\t<meta property=\"og:image:height\" content=\"580\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mvadmin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"mvadmin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.mariventyachts.com\\\/es\\\/nueva-fjord-36-xpress\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mariventyachts.com\\\/es\\\/nueva-fjord-36-xpress\\\/\"},\"author\":{\"name\":\"mvadmin\",\"@id\":\"https:\\\/\\\/www.mariventyachts.com\\\/#\\\/schema\\\/person\\\/cf7f9402b465b84ccf87e24f10df3d22\"},\"headline\":\"NUEVA FJORD 36 XPRESS\",\"datePublished\":\"2017-11-07T00:00:00+00:00\",\"dateModified\":\"2024-11-20T16:25:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.mariventyachts.com\\\/es\\\/nueva-fjord-36-xpress\\\/\"},\"wordCount\":630,\"publisher\":{\"@id\":\"https:\\\/\\\/www.mariventyachts.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mariventyachts.com\\\/es\\\/nueva-fjord-36-xpress\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mariventyachts.com\\\/wp-content\\\/uploads\\\/Fjord_36_xpress_exterior_Featured2.jpg\",\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.mariventyachts.com\\\/es\\\/nueva-fjord-36-xpress\\\/\",\"url\":\"https:\\\/\\\/www.mariventyachts.com\\\/es\\\/nueva-fjord-36-xpress\\\/\",\"name\":\"NUEVA FJORD 36 XPRESS - Marivent Yachts\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.mariventyachts.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.mariventyachts.com\\\/es\\\/nueva-fjord-36-xpress\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mariventyachts.com\\\/es\\\/nueva-fjord-36-xpress\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.mariventyachts.com\\\/wp-content\\\/uploads\\\/Fjord_36_xpress_exterior_Featured2.jpg\",\"datePublished\":\"2017-11-07T00:00:00+00:00\",\"dateModified\":\"2024-11-20T16:25:26+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.mariventyachts.com\\\/es\\\/nueva-fjord-36-xpress\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.mariventyachts.com\\\/es\\\/nueva-fjord-36-xpress\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mariventyachts.com\\\/es\\\/nueva-fjord-36-xpress\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.mariventyachts.com\\\/wp-content\\\/uploads\\\/Fjord_36_xpress_exterior_Featured2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mariventyachts.com\\\/wp-content\\\/uploads\\\/Fjord_36_xpress_exterior_Featured2.jpg\",\"width\":956,\"height\":580},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.mariventyachts.com\\\/es\\\/nueva-fjord-36-xpress\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.mariventyachts.com\\\/es\\\/b\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"NUEVA FJORD 36 XPRESS\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.mariventyachts.com\\\/#website\",\"url\":\"https:\\\/\\\/www.mariventyachts.com\\\/\",\"name\":\"Marivent Yachts\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.mariventyachts.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.mariventyachts.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.mariventyachts.com\\\/#organization\",\"name\":\"Marivent Yachts\",\"url\":\"https:\\\/\\\/www.mariventyachts.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.mariventyachts.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.mariventyachts.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/marivent-site-icon.jpg\",\"contentUrl\":\"https:\\\/\\\/www.mariventyachts.com\\\/wp-content\\\/uploads\\\/2024\\\/03\\\/marivent-site-icon.jpg\",\"width\":512,\"height\":512,\"caption\":\"Marivent Yachts\"},\"image\":{\"@id\":\"https:\\\/\\\/www.mariventyachts.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/mariventyachts\\\/\",\"https:\\\/\\\/www.instagram.com\\\/mariventyachts\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.mariventyachts.com\\\/#\\\/schema\\\/person\\\/cf7f9402b465b84ccf87e24f10df3d22\",\"name\":\"mvadmin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/582225c13c35a8d3bf811e8e4eb45f05353eb91aff88f557e56c4add20005099?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/582225c13c35a8d3bf811e8e4eb45f05353eb91aff88f557e56c4add20005099?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/582225c13c35a8d3bf811e8e4eb45f05353eb91aff88f557e56c4add20005099?s=96&d=mm&r=g\",\"caption\":\"mvadmin\"},\"sameAs\":[\"https:\\\/\\\/www.mariventyachts.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"NUEVA FJORD 36 XPRESS - Marivent Yachts","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mariventyachts.com\/es\/nueva-fjord-36-xpress\/","og_locale":"es_ES","og_type":"article","og_title":"NUEVA FJORD 36 XPRESS - Marivent Yachts","og_description":"Tras la feria n\u00e1utica internacional de Barcelona, hoy queremos dedicarle unas l\u00edneas al nuevo modelo de Fjord, la 36 Xpress.","og_url":"https:\/\/www.mariventyachts.com\/es\/nueva-fjord-36-xpress\/","og_site_name":"Marivent Yachts","article_publisher":"https:\/\/www.facebook.com\/mariventyachts\/","article_published_time":"2017-11-07T00:00:00+00:00","article_modified_time":"2024-11-20T16:25:26+00:00","og_image":[{"width":956,"height":580,"url":"https:\/\/www.mariventyachts.com\/wp-content\/uploads\/Fjord_36_xpress_exterior_Featured2.jpg","type":"image\/jpeg"}],"author":"mvadmin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"mvadmin","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mariventyachts.com\/es\/nueva-fjord-36-xpress\/#article","isPartOf":{"@id":"https:\/\/www.mariventyachts.com\/es\/nueva-fjord-36-xpress\/"},"author":{"name":"mvadmin","@id":"https:\/\/www.mariventyachts.com\/#\/schema\/person\/cf7f9402b465b84ccf87e24f10df3d22"},"headline":"NUEVA FJORD 36 XPRESS","datePublished":"2017-11-07T00:00:00+00:00","dateModified":"2024-11-20T16:25:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mariventyachts.com\/es\/nueva-fjord-36-xpress\/"},"wordCount":630,"publisher":{"@id":"https:\/\/www.mariventyachts.com\/#organization"},"image":{"@id":"https:\/\/www.mariventyachts.com\/es\/nueva-fjord-36-xpress\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mariventyachts.com\/wp-content\/uploads\/Fjord_36_xpress_exterior_Featured2.jpg","articleSection":["Sin categorizar"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.mariventyachts.com\/es\/nueva-fjord-36-xpress\/","url":"https:\/\/www.mariventyachts.com\/es\/nueva-fjord-36-xpress\/","name":"NUEVA FJORD 36 XPRESS - Marivent Yachts","isPartOf":{"@id":"https:\/\/www.mariventyachts.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mariventyachts.com\/es\/nueva-fjord-36-xpress\/#primaryimage"},"image":{"@id":"https:\/\/www.mariventyachts.com\/es\/nueva-fjord-36-xpress\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mariventyachts.com\/wp-content\/uploads\/Fjord_36_xpress_exterior_Featured2.jpg","datePublished":"2017-11-07T00:00:00+00:00","dateModified":"2024-11-20T16:25:26+00:00","breadcrumb":{"@id":"https:\/\/www.mariventyachts.com\/es\/nueva-fjord-36-xpress\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mariventyachts.com\/es\/nueva-fjord-36-xpress\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mariventyachts.com\/es\/nueva-fjord-36-xpress\/#primaryimage","url":"https:\/\/www.mariventyachts.com\/wp-content\/uploads\/Fjord_36_xpress_exterior_Featured2.jpg","contentUrl":"https:\/\/www.mariventyachts.com\/wp-content\/uploads\/Fjord_36_xpress_exterior_Featured2.jpg","width":956,"height":580},{"@type":"BreadcrumbList","@id":"https:\/\/www.mariventyachts.com\/es\/nueva-fjord-36-xpress\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mariventyachts.com\/es\/b\/"},{"@type":"ListItem","position":2,"name":"NUEVA FJORD 36 XPRESS"}]},{"@type":"WebSite","@id":"https:\/\/www.mariventyachts.com\/#website","url":"https:\/\/www.mariventyachts.com\/","name":"Marivent Yachts","description":"","publisher":{"@id":"https:\/\/www.mariventyachts.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mariventyachts.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mariventyachts.com\/#organization","name":"Marivent Yachts","url":"https:\/\/www.mariventyachts.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mariventyachts.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.mariventyachts.com\/wp-content\/uploads\/2024\/03\/marivent-site-icon.jpg","contentUrl":"https:\/\/www.mariventyachts.com\/wp-content\/uploads\/2024\/03\/marivent-site-icon.jpg","width":512,"height":512,"caption":"Marivent Yachts"},"image":{"@id":"https:\/\/www.mariventyachts.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/mariventyachts\/","https:\/\/www.instagram.com\/mariventyachts\/"]},{"@type":"Person","@id":"https:\/\/www.mariventyachts.com\/#\/schema\/person\/cf7f9402b465b84ccf87e24f10df3d22","name":"mvadmin","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/582225c13c35a8d3bf811e8e4eb45f05353eb91aff88f557e56c4add20005099?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/582225c13c35a8d3bf811e8e4eb45f05353eb91aff88f557e56c4add20005099?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/582225c13c35a8d3bf811e8e4eb45f05353eb91aff88f557e56c4add20005099?s=96&d=mm&r=g","caption":"mvadmin"},"sameAs":["https:\/\/www.mariventyachts.com"]}]}},"_links":{"self":[{"href":"https:\/\/www.mariventyachts.com\/es\/wp-json\/wp\/v2\/posts\/2688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.mariventyachts.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mariventyachts.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mariventyachts.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mariventyachts.com\/es\/wp-json\/wp\/v2\/comments?post=2688"}],"version-history":[{"count":2,"href":"https:\/\/www.mariventyachts.com\/es\/wp-json\/wp\/v2\/posts\/2688\/revisions"}],"predecessor-version":[{"id":4545,"href":"https:\/\/www.mariventyachts.com\/es\/wp-json\/wp\/v2\/posts\/2688\/revisions\/4545"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mariventyachts.com\/es\/wp-json\/wp\/v2\/media\/2340"}],"wp:attachment":[{"href":"https:\/\/www.mariventyachts.com\/es\/wp-json\/wp\/v2\/media?parent=2688"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mariventyachts.com\/es\/wp-json\/wp\/v2\/categories?post=2688"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mariventyachts.com\/es\/wp-json\/wp\/v2\/tags?post=2688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}